{"id":235,"count":16,"description":"","link":"https:\/\/www.zanolli.it\/en\/cat_blog\/zanolli-from-the-world\/","name":"Zanolli from the world","slug":"zanolli-from-the-world","taxonomy":"cat_blog","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Zanolli from the world Archives - Zanolli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zanolli from the world Archives - Zanolli\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanolli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/\",\"url\":\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/\",\"name\":\"Zanolli from the world Archives - Zanolli\",\"isPartOf\":{\"@id\":\"https:\/\/www.zanolli.it\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/prodzanolli.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zanolli dal mondo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zanolli.it\/#website\",\"url\":\"https:\/\/www.zanolli.it\/\",\"name\":\"Zanolli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zanolli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zanolli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zanolli.it\/#organization\",\"name\":\"Zanolli\",\"url\":\"https:\/\/www.zanolli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"width\":130,\"height\":39,\"caption\":\"Zanolli\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zanolli from the world Archives - Zanolli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/","og_locale":"en_US","og_type":"article","og_title":"Zanolli from the world Archives - Zanolli","og_url":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/","og_site_name":"Zanolli","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/","url":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/","name":"Zanolli from the world Archives - Zanolli","isPartOf":{"@id":"https:\/\/www.zanolli.it\/#website"},"breadcrumb":{"@id":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.zanolli.it\/cat_blog\/zanolli-dal-mondo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodzanolli.it\/en\/"},{"@type":"ListItem","position":2,"name":"Zanolli dal mondo"}]},{"@type":"WebSite","@id":"https:\/\/www.zanolli.it\/#website","url":"https:\/\/www.zanolli.it\/","name":"Zanolli","description":"","publisher":{"@id":"https:\/\/www.zanolli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zanolli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.zanolli.it\/#organization","name":"Zanolli","url":"https:\/\/www.zanolli.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","width":130,"height":39,"caption":"Zanolli"},"image":{"@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zanolli.it\/en\/wp-json\/wp\/v2\/cat_blog\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanolli.it\/en\/wp-json\/wp\/v2\/cat_blog"}],"about":[{"href":"https:\/\/www.zanolli.it\/en\/wp-json\/wp\/v2\/taxonomies\/cat_blog"}],"wp:post_type":[{"href":"https:\/\/www.zanolli.it\/en\/wp-json\/wp\/v2\/blog?cat_blog=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}