{"id":13456,"date":"2019-02-20T00:00:00","date_gmt":"2019-02-19T23:00:00","guid":{"rendered":"http:\/\/zanolli.mck.lcl\/blog\/paco-torreblanca-tengamos-la-mente-abierta-pero-sin-perder-nuestra-esencia\/"},"modified":"2023-02-02T17:14:54","modified_gmt":"2023-02-02T16:14:54","slug":"paco-torreblanca-tengamos-la-mente-abierta-pero-sin-perder-nuestra-esencia","status":"publish","type":"blog","link":"https:\/\/www.zanolli.it\/es\/blog\/paco-torreblanca-tengamos-la-mente-abierta-pero-sin-perder-nuestra-esencia\/","title":{"rendered":"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10287 alignleft\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/retrato-Paco-con-tarta-scaled.jpg\" alt=\"\" width=\"303\" height=\"202\" \/>Profesor de renombre y galardonado con numerosos premios, aunque siempre humilde y cordial. El Maestro Paco Torreblanca colabora desde a\u00f1os con Zanolli y ha adoptado nuestros hornos en su Escuela Torreblanca. Para prepararles las papilas en vista de Intersicop, hemos horneado una sabrosa entrevista con el Maestro. \u00a1Vengan a visitarnos en nuestro stand para ver en vivo el showcooking de Paco Torreblanca y su Escuela!<\/p>\n<p><strong>Maestro, cu\u00e9ntenos acerca de su experiencia en la transmisi\u00f3n TV Best Bakery Italia: \u00bfQu\u00e9 es lo que m\u00e1s le impact\u00f3? \u00bfCu\u00e1les diferencias ha encontrado respecto a la pasteler\u00eda espa\u00f1ola o internacional, en general?\u00a0 \u00a0<\/strong><\/p>\n<p><strong>Paco Torreblanca:<\/strong> Para m\u00ed el programa de televisi\u00f3n ha sido una experiencia extraordinaria, me ha permitido conocer la pasteler\u00eda italiana del norte al sur y he encontrado ciertas similitudes en algunos pasteles del sur de Italia con el sur de Espa\u00f1a y el norte como en Espa\u00f1a mucho m\u00e1s industrializada, pero para m\u00ed es muy importante que nunca perdamos nuestra identidad.<\/p>\n<p><strong>Adem\u00e1s de ser un reconocido chef de reposter\u00eda, tambi\u00e9n es un exitoso empresario y un profesor muy apreciado por los alumnos. <\/strong><strong>\u00bfFue \u00e9ste su proyecto desde el principio? <\/strong><strong>\u00bfC\u00f3mo ha evolucionado su actividad comercial a lo largo de los a\u00f1os? \u00bfHay otros proyectos a desarrollar para el futuro?\u00a0 <\/strong><\/p>\n<p><strong>P.T.:<\/strong> Para m\u00ed, lo m\u00e1s importante siempre ha sido mi profesi\u00f3n y siempre intentando crear nuevas ideas y conceptos creativos cuando estoy con mis alumnos. Intento transmitir mi filosof\u00eda de trabajo y hacer que se apasionen por esta profesi\u00f3n. Proyectos de futuro, continuar con mi escuela y potenciar mi otra escuela en China.<\/p>\n<p><strong>La fama de muchos chef y reposteros Europeos se extiende siempre m\u00e1s all\u00e1 de las fronteras nacionales, y se multiplican los proyectos en pa\u00edses con tradiciones culinarias bastante diferentes (pensamos, por ejemplo, China). \u00bfExiste un proceso de adaptaci\u00f3n a los recursos y gustos locales cuando se trata de pasteler\u00eda de alto nivel? \u00bfEsto puede resultar una p\u00e9rdida de identidad o la contaminaci\u00f3n, en cambio, puede estimular la creatividad? <\/strong><strong>\u00bfAlg\u00fan ejemplo?<\/strong><\/p>\n<p><strong>P.T.:<\/strong> Siempre que exportamos nuestras ideas y productos a otras culturas diferentes es en mi opini\u00f3n importante mantener nuestra propia identidad y nuestra cultura gastron\u00f3mica sin caer en el error de mezclas, pero siempre hay que tener la mente abierta a nuevas materias. Por ejemplo, si en nuestra cultura contamos con una tarta de lim\u00f3n, y sustituimos el lim\u00f3n por el Yuzu, estamos manteniendo nuestra identidad sin perder nuestra esencia.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Como Ud. bien sabe, muchas empresas en Italia son de propiedad familiar y conducidas por los integrantes del mismo grupo familiar. Tambi\u00e9n en su caso, la transmisi\u00f3n de conocimientos y la asignaci\u00f3n de roles de responsabilidad a su familia parece ser una f\u00f3rmula exitosa. \u00bfC\u00f3mo se vive la relaci\u00f3n laboral en estos casos?<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10285 alignright\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/PACO-Y-JACOB-TORREBLANCA-scaled.jpg\" alt=\"\" width=\"254\" height=\"381\" \/> <\/strong><\/p>\n<p><strong>P.T.:<\/strong> En Espa\u00f1a como en Italia, hay una gran tradici\u00f3n familiar muy antigua. La relaci\u00f3n no siempre es f\u00e1cil porque las nuevas generaciones tienen otra forma de pensar pero debemos de ser inteligentes y dejarles paso y si nos piden consejo, aconsejarlos.<\/p>\n<p><strong>\u00a0<\/strong><strong>Cu\u00e9ntenos algo sobre su famoso panet\u00f3n. \u00bfCu\u00e1ndo le vino la inspiraci\u00f3n de realizarlo? \u00bfEsperaba este \u00e9xito? \u00a0<\/strong><\/p>\n<p><strong>P.T.:<\/strong> Jam\u00e1s pens\u00e9 el \u00e9xito del panettone en Espa\u00f1a y en otros pa\u00edses. Doy gracias a la cultura italiana del panettone artesano, que me hizo ver la bondad de este producto y tambi\u00e9n a mis amigos Iginio Massari, Achille Zola y a Vittorio Santoro por sus consejos que me ayudaron tanto y que he interpretado a mi manera.<\/p>\n<p><strong>Se est\u00e1 prestando mucha atenci\u00f3n al uso de ingredientes a cero km o bajo impacto ambiental en la cocina, \u00bfes igual en la reposter\u00eda? \u00bfCu\u00e1les son los principales desaf\u00edos y oportunidades de esta elecci\u00f3n?\u00a0\u00a0\u00a0\u00a0 \u00a0<\/strong><\/p>\n<p><strong>P.T.:<\/strong> Siempre que puedo, efectivamente utilizo productos de mi regi\u00f3n y de Espa\u00f1a. No siempre es posible pero estoy convencido que es el camino a seguir porque de esta manera nuestras recetas tendr\u00e1n la autenticidad de cada uno de nuestros pa\u00edses y nuestras regiones.<\/p>\n<p><strong>El problema de la reducci\u00f3n de los desperdicios en el mundo de la restauraci\u00f3n es muy importante para algunos profesionales y consumidores. \u00bfQu\u00e9 medidas utiliza en su m\u00e9todo de trabajo para adoptar este enfoque? <\/strong><\/p>\n<p><strong>P.T.:<\/strong> Este es un problema bastante grave. Intento ajustar nuestras recetas al m\u00e1ximo para que queden los m\u00ednimos residuos y utilizando todo tipo de embalajes reciclados, no es un tema f\u00e1cil. Recuerdo cuando aprend\u00ed en Par\u00eds que ten\u00edamos unos porcentajes baj\u00edsimos de restos en la pasteler\u00eda, no s\u00e9 si ser\u00eda porque las materias primas eran lo m\u00e1s costoso y ten\u00edan mucha disciplina. Hoy la mano de obra supera a la materia prima, quiz\u00e1s ese sea el problema de tanto residuo.<\/p>\n<p><strong>En su experiencia, seguramente habr\u00e1 observado una evoluci\u00f3n en el gusto y la est\u00e9tica de las creaciones de pasteler\u00eda. <\/strong><strong>\u00bfHa notado alguna tendencia dominante? C\u00f3mo interact\u00faan profesionales y consumidores? \u00bfHay una influencia mutua? <\/strong><\/p>\n<p><strong>P.T.:<\/strong> Qu\u00e9 duda cabe, ciertos profesionales tienen una importancia en las tendencias y las proponen. Muchas tienen \u00e9xito, pero para m\u00ed siempre ha tenido mayor importancia el sabor y la est\u00e9tica que tambi\u00e9n es muy importante; si conseguimos las dos, la propuesta es casi perfecta. Siempre he pensado que mis clientes apreciaban mis propuestas y por eso cada a\u00f1o ofrec\u00eda cada 6 meses una propuesta diferente, en funci\u00f3n de la estaci\u00f3n del a\u00f1o, invierno o verano. En mi opini\u00f3n, pienso que es una manera de mantener un contacto creativo y atractivo para el consumidor.<\/p>\n<p><strong>Invisiblemente, incluso los equipos son un ingrediente fundamental en el mundo de la reposter\u00eda. \u00bfQu\u00e9 es lo m\u00e1s importante para un pastelero de su nivel? En su larga experiencia, \u00bfqu\u00e9 es lo que le ha impresionado m\u00e1s en la evoluci\u00f3n de las herramientas de trabajo? \u00bfCu\u00e1les son los l\u00edmites y ventajas del progreso tecnol\u00f3gico?<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10284 alignright\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Torreblanca_Zaonlli_Polis-scaled.jpg\" alt=\"\" width=\"328\" height=\"243\" \/> <\/strong><\/p>\n<p><strong>P.T.:<\/strong> Los nuevos materiales, moldes, siliconas, congelaci\u00f3n y otros han cambiado el mundo de la pasteler\u00eda. Nos ha permitido nuevas formas que hace a\u00f1os eran imposibles, a nivel de est\u00e9tica y decoraci\u00f3n y tambi\u00e9n las nuevas m\u00e1quinas, utensilios y sistemas de congelaci\u00f3n han hecho que nuestra profesi\u00f3n sea m\u00e1s humana.<\/p>\n<p><strong>Desea compartir alg\u00fan consejo con los aspirantes pasteleros\/as? <\/strong><\/p>\n<p><strong>P.T.:<\/strong> Mi consejo en esta profesi\u00f3n, es pasi\u00f3n, esfuerzo, creatividad, sacrificio, a m\u00ed me lo ha dado todo esta profesi\u00f3n. Yo digo que con esfuerzo y trabajo conseguir\u00e9is todo lo que propong\u00e1is.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Profesor de renombre y galardonado con numerosos premios, aunque siempre humilde y cordial. El Maestro Paco Torreblanca colabora desde a\u00f1os con Zanolli y ha adoptado nuestros hornos en su Escuela Torreblanca. Para prepararles las papilas en vista de Intersicop, hemos horneado una sabrosa entrevista con el Maestro. \u00a1Vengan a visitarnos en nuestro stand para ver [&hellip;]<\/p>\n","protected":false},"author":849,"featured_media":12833,"template":"","cat_blog":[231],"class_list":["post-13456","blog","type-blog","status-publish","has-post-thumbnail","hentry","cat_blog-discovery-es"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli\" \/>\n<meta property=\"og:description\" content=\"Profesor de renombre y galardonado con numerosos premios, aunque siempre humilde y cordial. El Maestro Paco Torreblanca colabora desde a\u00f1os con Zanolli y ha adoptado nuestros hornos en su Escuela Torreblanca. Para prepararles las papilas en vista de Intersicop, hemos horneado una sabrosa entrevista con el Maestro. \u00a1Vengan a visitarnos en nuestro stand para ver [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanolli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T16:14:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"420\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/\",\"url\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/\",\"name\":\"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli\",\"isPartOf\":{\"@id\":\"https:\/\/www.zanolli.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg\",\"datePublished\":\"2019-02-19T23:00:00+00:00\",\"dateModified\":\"2023-02-02T16:14:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg\",\"width\":420,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/prodzanolli.it\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zanolli.it\/#website\",\"url\":\"https:\/\/www.zanolli.it\/\",\"name\":\"Zanolli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zanolli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zanolli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zanolli.it\/#organization\",\"name\":\"Zanolli\",\"url\":\"https:\/\/www.zanolli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"width\":130,\"height\":39,\"caption\":\"Zanolli\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/","og_locale":"es_ES","og_type":"article","og_title":"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli","og_description":"Profesor de renombre y galardonado con numerosos premios, aunque siempre humilde y cordial. El Maestro Paco Torreblanca colabora desde a\u00f1os con Zanolli y ha adoptado nuestros hornos en su Escuela Torreblanca. Para prepararles las papilas en vista de Intersicop, hemos horneado una sabrosa entrevista con el Maestro. \u00a1Vengan a visitarnos en nuestro stand para ver [&hellip;]","og_url":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/","og_site_name":"Zanolli","article_modified_time":"2023-02-02T16:14:54+00:00","og_image":[{"width":420,"height":360,"url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/","url":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/","name":"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0 - Zanolli","isPartOf":{"@id":"https:\/\/www.zanolli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage"},"image":{"@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg","datePublished":"2019-02-19T23:00:00+00:00","dateModified":"2023-02-02T16:14:54+00:00","breadcrumb":{"@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#primaryimage","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/DA-PAGINA-FB-ESCUELA-470-360_o.jpg","width":420,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.zanolli.it\/blog\/paco-torreblanca-teniamo-la-mente-aperta-ma-senza-perdere-la-nostra-essenza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodzanolli.it\/es\/"},{"@type":"ListItem","position":2,"name":"Paco Torreblanca: \u201cTengamos la mente abierta, pero sin perder nuestra esencia\u201d\u00a0 \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/www.zanolli.it\/#website","url":"https:\/\/www.zanolli.it\/","name":"Zanolli","description":"","publisher":{"@id":"https:\/\/www.zanolli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zanolli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.zanolli.it\/#organization","name":"Zanolli","url":"https:\/\/www.zanolli.it\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","width":130,"height":39,"caption":"Zanolli"},"image":{"@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/blog\/13456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/users\/849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/media\/12833"}],"wp:attachment":[{"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/media?parent=13456"}],"wp:term":[{"taxonomy":"cat_blog","embeddable":true,"href":"https:\/\/www.zanolli.it\/es\/wp-json\/wp\/v2\/cat_blog?post=13456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}