{"id":13322,"date":"2020-07-20T00:00:00","date_gmt":"2020-07-19T22:00:00","guid":{"rendered":"http:\/\/zanolli.mck.lcl\/blog\/comment-bien-choisir-son-petrin\/"},"modified":"2023-02-02T17:14:18","modified_gmt":"2023-02-02T16:14:18","slug":"comment-bien-choisir-son-petrin","status":"publish","type":"blog","link":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/","title":{"rendered":"Comment bien choisir son p\u00e9trin ?"},"content":{"rendered":"<p><strong>Comida<\/strong> est la ligne de Zanolli qui depuis 1977 r\u00e9alise des machines pour la pr\u00e9paration des p\u00e2tes pour les pizz\u00e9rias, les boulangeries et les p\u00e2tisseries.<\/p>\n<p>L&rsquo;instrument indispensable \u00e0 tous les laboratoires est le p\u00e9trin. Les exigences de production, les dimensions du laboratoire, et les typologies des diff\u00e9rentes p\u00e2tes d\u00e9terminent le meilleur choix du p\u00e9trin. Comida offre la possibilit\u00e9 de choisir parmi <strong>6 lignes de p\u00e9trins<\/strong>, chacune ayant des mod\u00e8les diff\u00e9rents selon les n\u00e9cessit\u00e9s de production. Tous les p\u00e9trins ont comme points communs la r\u00e9sistance, la s\u00e9curit\u00e9, et la facilit\u00e9 d\u2019utilisation. Pour vous orienter rapidement, passons en revue la gamme en mettant en \u00e9vidence leurs principales caract\u00e9ristiques.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10665 alignleft\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg\" alt=\"Impastatrice Galassia_Comida by Zanolli\" width=\"128\" height=\"192\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/galassia-pizza\/\" target=\"_blank\" rel=\"noopener\">GALASSIA<\/a> \u2013 P\u00c9TRIN \u00c0 SPIRALE POUR PIZZA <\/strong><\/p>\n<p>Versatile et compact, Galassia Pizza est un <strong>best-seller<\/strong> chez les pizzaiolos, car il offre le choix entre 7 capacit\u00e9s diff\u00e9rentes de cuve<strong>: de 8 \u00e0 60 kg<\/strong>. Il est disponible \u00e0 une ou deux vitesses. La <strong>transmission par cha\u00eene<\/strong> garantit longue dur\u00e9e et r\u00e9sistance durant la phase de p\u00e9trissage. Pour les mod\u00e8les plus compacts, il existe des versions <strong>\u00e0<\/strong> <strong>t\u00eate relevable, avec ou sans cuve extractible<\/strong>. Ce p\u00e9trin est dot\u00e9 d\u2019une spirale robuste et d\u2019un pivot casse-p\u00e2te, tous les deux en acier inoxydable. Il est adapt\u00e9 pour pr\u00e9parer des p\u00e2tes avec un taux d\u2019humidit\u00e9 minimum de 50%. Le kit des roues est en option.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10664 alignright\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia-PLUS_RGB.jpg\" alt=\"Impastatrice Galassia PLUS Comida by Zanolli\" width=\"160\" height=\"194\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/galassia-plus\/\" target=\"_blank\" rel=\"noopener\">GALASSIA PLUS<\/a> \u2013 P\u00c9TRIN \u00c0 SPIRALE POUR PIZZA \u2013 P\u00c2TES DURES<\/strong><\/p>\n<p>Une nouveaut\u00e9 dans le catalogue Comida: une version <strong>encore plus puissante et robuste<\/strong>, particuli\u00e8rement adapt\u00e9e pour les p\u00e2tes dont le taux d\u2019<strong>hydratation est bas<\/strong>. Capacit\u00e9s disponibles\u00a0: <strong>25 kg<\/strong><strong> ou 35 Kg<\/strong>, toutes les deux \u00e0 deux vitesses. Tous les accessoires sont en acier inoxydable. Une <strong>solide structure<\/strong> assure le fonctionnement et la stabilit\u00e9 m\u00eame avec des p\u00e2tes peu hydrat\u00e9es, et les roues de s\u00e9rie facilitent le d\u00e9placement. La forme allong\u00e9e particuli\u00e8re de la spirale et la forme arrondie de la cuve permettent de recueillir parfaitement la p\u00e2te et de la d\u00e9tacher facilement du fond de la cuve.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10666 alignleft\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Impastatrice_Galassia_Pane.jpg\" alt=\"Impastatrice_Galassia_Pane Comida by Zanolli\" width=\"157\" height=\"209\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/galassia-pane\/\" target=\"_blank\" rel=\"noopener\">GALASSIA PAIN<\/a> \u2013 P\u00c9TRIN \u00c0 SPIRALE POUR PAIN<\/strong><\/p>\n<p>Dot\u00e9 d\u2019une m\u00e9canique tr\u00e8s robuste, ce p\u00e9trin est particuli\u00e8rement <strong>adapt\u00e9 aux boulangeries<\/strong>, o\u00f9 les volumes de production sont importants. 3 mod\u00e8les sont disponibles\u00a0:<strong> 60, 80 et 120 kg, tous \u00e0 deux vitesses<\/strong>. La cuve est fixe et en acier inoxydable comme la spirale. L\u2019excellent rapport entre la spirale et la cuve permet une parfaite oxyg\u00e9nation. Il peut pr\u00e9parer les p\u00e2tes avec un taux d\u2019hydratation d\u2019au moins 50%. Les roues sont incluses. Il est dot\u00e9 de deux moteurs qui permettent l\u2019inversion de la cuve. Galassia Pain a une <strong>double minuterie<\/strong> de s\u00e9rie pour r\u00e9gler le temps de pr\u00e9paration des 2 vitesses. Il est possible de l\u2019utiliser en mode <strong>manuel, automatique ou semi-automatique<\/strong>. Les roues et les pieds sont aussi de s\u00e9rie et garantissent la stabilit\u00e9 durant le fonctionnement. Il est dot\u00e9 d\u2019un pivot avec pied qui aide \u00e0 recueillir les p\u00e2tes les plus hydrat\u00e9es.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-10661 alignright\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Demetra30.jpg\" alt=\"Impastatrice Demetra 30 Comida by Zanolli\" width=\"248\" height=\"164\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/demetra\/\" target=\"_blank\" rel=\"noopener\">DEMETRA<\/a> \u2013 P\u00c9TRIN \u00c0 FOURCHE MULTIFONCTIONS<\/strong><\/p>\n<p>L\u2019ustensile \u00e0 fourche tourne sur des roulements \u00e0 billes et permet d\u2019<strong>amalgamer de fa\u00e7on homog\u00e8ne<\/strong> les ingr\u00e9dients <strong>sans r\u00e9chauffer <\/strong>les p\u00e2tes. Sa capacit\u00e9 est de 30 kg, mais il p\u00e9trit rapidement m\u00eame les p\u00e2tes de petit volume. Il est disponible dans les versions \u00e0 <strong>une ou deux vitesses<\/strong>, tous les deux poss\u00e8dent une <strong>minuterie<\/strong>. Il peut p\u00e9trir des p\u00e2tes consistantes, avec une quantit\u00e9 minimale d\u2019eau de 50%. Fourche, couvercle et cuve sont en acier inoxydable. La rotation simultan\u00e9e et oppos\u00e9e de l\u2019ustensile et de la cuve aide \u00e0 recueillir le m\u00e9lange p\u00e9tri. Des chariots avec des roues de 10 cm ou 40 cm sont fournis en option.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10662 alignleft\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/demetra60.jpg\" alt=\"Impastatrice Demetra pane Comida by Zanolli\" width=\"148\" height=\"194\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/demetra-pain\/\" target=\"_blank\" rel=\"noopener\">DEMETRA PAIN<\/a> \u2013 P\u00c9TRIN \u00c0 FOURCHE POUR PAIN ET P\u00c2TISSERIE<\/strong><\/p>\n<p>Ce p\u00e9trin \u00e0 fourche est particuli\u00e8rement indiqu\u00e9 pour <strong>amalgamer, sans les r\u00e9chauffer,\u00a0<\/strong>les p\u00e2tes dures et <strong>consistantes<\/strong> typiques de la panification. Le mouvement de la fourche garantit une excellente oxyg\u00e9nation de la p\u00e2te, en rendant plus friable le produit fini. Les mod\u00e8les <strong>de 35 kg et de 60 kg sont disponibles, tous les deux \u00e0 deux vitesses. La quantit\u00e9 d\u2019hydratation minimale conseill\u00e9e de la p\u00e2te est de 50%. La cuve et le couvercle sont en acier inoxydable. La fente sur le couvercle permet de contr\u00f4ler la p\u00e2te et d\u2019ins\u00e9rer les ingr\u00e9dients m\u00eame durant le p\u00e9trissage.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-10663 alignright\" src=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Eracle_bracci.jpg\" alt=\"Impastatrice Eracle Comida by Zanolli\" width=\"173\" height=\"260\" \/><a href=\"https:\/\/www.zanollifours.fr\/p\/eracle\/\" target=\"_blank\" rel=\"noopener\">ERACLE<\/a> \u2013 P\u00c9TRIN \u00c0 BRAS PLONGEANTS\u00a0 <\/strong><\/p>\n<p>Le mouvement des bras plongeants a \u00e9t\u00e9 \u00e9tudi\u00e9 pour reproduire celui humain. <strong>Les bras soul\u00e8vent la p\u00e2te<\/strong>, pour permettre son oxyg\u00e9nation et \u00e9viter qu\u2019elle se r\u00e9chauffe. De plus, ils permettent la distribution r\u00e9guli\u00e8re des \u00e9l\u00e9ments en suspension. Ce p\u00e9trin est utile par exemple pour la r\u00e9alisation des p\u00e2tes pour les panettones, et il est souvent utilis\u00e9 dans les p\u00e2tisseries et les industries de la confiserie, mais aussi dans les pizz\u00e9rias qui d\u00e9sirent <strong>tenir sous contr\u00f4le la temp\u00e9rature de la p\u00e2te <\/strong>durant tout le p\u00e9trissage. Les diff\u00e9rentes capacit\u00e9s disponibles d\u2019Eracle de Comida sont<strong> 50, 60, 80 et 100 kg<\/strong>, tous \u00e0 deux vitesses. Les bras, la cuve et la protection sont en acier inoxydable. Il peut travailler des p\u00e2tes aussi bien consistantes que plus moelleuses qui pr\u00e9voient l\u2019ajout progressif des ingr\u00e9dients.<\/p>\n<p>&nbsp;<\/p>\n<p>N.B.: le <strong>voltage Standard<\/strong> des machines Comida est de: <strong>400Vac 3 50Hz<\/strong>. Des voltages alternatifs sont disponibles sur demande et apr\u00e8s approbation du bureau technique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comida est la ligne de Zanolli qui depuis 1977 r\u00e9alise des machines pour la pr\u00e9paration des p\u00e2tes pour les pizz\u00e9rias, les boulangeries et les p\u00e2tisseries. L&rsquo;instrument indispensable \u00e0 tous les laboratoires est le p\u00e9trin. Les exigences de production, les dimensions du laboratoire, et les typologies des diff\u00e9rentes p\u00e2tes d\u00e9terminent le meilleur choix du p\u00e9trin. Comida [&hellip;]<\/p>\n","protected":false},"author":849,"featured_media":12950,"template":"","cat_blog":[230],"class_list":["post-13322","blog","type-blog","status-publish","has-post-thumbnail","hentry","cat_blog-discovery-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comment bien choisir son p\u00e9trin ? - Zanolli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment bien choisir son p\u00e9trin ? - Zanolli\" \/>\n<meta property=\"og:description\" content=\"Comida est la ligne de Zanolli qui depuis 1977 r\u00e9alise des machines pour la pr\u00e9paration des p\u00e2tes pour les pizz\u00e9rias, les boulangeries et les p\u00e2tisseries. L&rsquo;instrument indispensable \u00e0 tous les laboratoires est le p\u00e9trin. Les exigences de production, les dimensions du laboratoire, et les typologies des diff\u00e9rentes p\u00e2tes d\u00e9terminent le meilleur choix du p\u00e9trin. Comida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanolli\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-02T16:14:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"625\" \/>\n\t<meta property=\"og:image:height\" content=\"940\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/\",\"url\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/\",\"name\":\"Comment bien choisir son p\u00e9trin ? - Zanolli\",\"isPartOf\":{\"@id\":\"https:\/\/www.zanolli.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg\",\"datePublished\":\"2020-07-19T22:00:00+00:00\",\"dateModified\":\"2023-02-02T16:14:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg\",\"width\":625,\"height\":940},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/prodzanolli.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comment bien choisir son p\u00e9trin ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zanolli.it\/#website\",\"url\":\"https:\/\/www.zanolli.it\/\",\"name\":\"Zanolli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zanolli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zanolli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zanolli.it\/#organization\",\"name\":\"Zanolli\",\"url\":\"https:\/\/www.zanolli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"width\":130,\"height\":39,\"caption\":\"Zanolli\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment bien choisir son p\u00e9trin ? - Zanolli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment bien choisir son p\u00e9trin ? - Zanolli","og_description":"Comida est la ligne de Zanolli qui depuis 1977 r\u00e9alise des machines pour la pr\u00e9paration des p\u00e2tes pour les pizz\u00e9rias, les boulangeries et les p\u00e2tisseries. L&rsquo;instrument indispensable \u00e0 tous les laboratoires est le p\u00e9trin. Les exigences de production, les dimensions du laboratoire, et les typologies des diff\u00e9rentes p\u00e2tes d\u00e9terminent le meilleur choix du p\u00e9trin. Comida [&hellip;]","og_url":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/","og_site_name":"Zanolli","article_modified_time":"2023-02-02T16:14:18+00:00","og_image":[{"width":625,"height":940,"url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/","url":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/","name":"Comment bien choisir son p\u00e9trin ? - Zanolli","isPartOf":{"@id":"https:\/\/www.zanolli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage"},"image":{"@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg","datePublished":"2020-07-19T22:00:00+00:00","dateModified":"2023-02-02T16:14:18+00:00","breadcrumb":{"@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#primaryimage","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2023\/02\/Galassia_vasca01.jpg","width":625,"height":940},{"@type":"BreadcrumbList","@id":"https:\/\/www.zanolli.it\/fr\/blog\/comment-bien-choisir-son-petrin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodzanolli.it\/fr\/"},{"@type":"ListItem","position":2,"name":"Comment bien choisir son p\u00e9trin ?"}]},{"@type":"WebSite","@id":"https:\/\/www.zanolli.it\/#website","url":"https:\/\/www.zanolli.it\/","name":"Zanolli","description":"","publisher":{"@id":"https:\/\/www.zanolli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zanolli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.zanolli.it\/#organization","name":"Zanolli","url":"https:\/\/www.zanolli.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","width":130,"height":39,"caption":"Zanolli"},"image":{"@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/blog\/13322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/blog"}],"about":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/types\/blog"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/users\/849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/media\/12950"}],"wp:attachment":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/media?parent=13322"}],"wp:term":[{"taxonomy":"cat_blog","embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/cat_blog?post=13322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}