{"id":3314,"date":"2022-01-13T12:14:39","date_gmt":"2022-01-13T11:14:39","guid":{"rendered":"https:\/\/zanolli.staging2.welcomedigital.it\/prodotti\/galassia-pizza\/"},"modified":"2024-09-09T10:00:52","modified_gmt":"2024-09-09T08:00:52","slug":"galassia-pizza","status":"publish","type":"products","link":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/","title":{"rendered":"GALASSIA PIZZA"},"content":{"rendered":"\r\n<p>La technologie la plus moderne et la simplicit\u00e9 du travail se fondent dans Galassia pour innover l\u2019art de la pizza.<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>La technologie la plus moderne et la simplicit\u00e9 du travail se fondent dans Galassia pour innover l\u2019art de la pizza.<\/p>\n","protected":false},"author":2,"featured_media":28352,"template":"","campi-applicativi":[87,65],"tipologie":[91,153],"caratteristiche":[],"class_list":["post-3314","products","type-products","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>GALASSIA PIZZA - Zanolli<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GALASSIA PIZZA - Zanolli\" \/>\n<meta property=\"og:description\" content=\"La technologie la plus moderne et la simplicit\u00e9 du travail se fondent dans Galassia pour innover l\u2019art de la pizza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/\" \/>\n<meta property=\"og:site_name\" content=\"Zanolli\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-09T08:00:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1712\" \/>\n\t<meta property=\"og:image:height\" content=\"1748\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/\",\"url\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/\",\"name\":\"GALASSIA PIZZA - Zanolli\",\"isPartOf\":{\"@id\":\"https:\/\/www.zanolli.it\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png\",\"datePublished\":\"2022-01-13T11:14:39+00:00\",\"dateModified\":\"2024-09-09T08:00:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png\",\"width\":1712,\"height\":1748},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/prodzanolli.it\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GALASSIA PIZZA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.zanolli.it\/#website\",\"url\":\"https:\/\/www.zanolli.it\/\",\"name\":\"Zanolli\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/www.zanolli.it\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.zanolli.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.zanolli.it\/#organization\",\"name\":\"Zanolli\",\"url\":\"https:\/\/www.zanolli.it\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"contentUrl\":\"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png\",\"width\":130,\"height\":39,\"caption\":\"Zanolli\"},\"image\":{\"@id\":\"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GALASSIA PIZZA - Zanolli","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/","og_locale":"fr_FR","og_type":"article","og_title":"GALASSIA PIZZA - Zanolli","og_description":"La technologie la plus moderne et la simplicit\u00e9 du travail se fondent dans Galassia pour innover l\u2019art de la pizza.","og_url":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/","og_site_name":"Zanolli","article_modified_time":"2024-09-09T08:00:52+00:00","og_image":[{"width":1712,"height":1748,"url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/","url":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/","name":"GALASSIA PIZZA - Zanolli","isPartOf":{"@id":"https:\/\/www.zanolli.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage"},"image":{"@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png","datePublished":"2022-01-13T11:14:39+00:00","dateModified":"2024-09-09T08:00:52+00:00","breadcrumb":{"@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#primaryimage","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/01\/Galassia-pizza_logo-zanolli.png","width":1712,"height":1748},{"@type":"BreadcrumbList","@id":"https:\/\/www.zanolli.it\/fr\/produits\/galassia-pizza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/prodzanolli.it\/fr\/"},{"@type":"ListItem","position":2,"name":"GALASSIA PIZZA"}]},{"@type":"WebSite","@id":"https:\/\/www.zanolli.it\/#website","url":"https:\/\/www.zanolli.it\/","name":"Zanolli","description":"","publisher":{"@id":"https:\/\/www.zanolli.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.zanolli.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.zanolli.it\/#organization","name":"Zanolli","url":"https:\/\/www.zanolli.it\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/","url":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","contentUrl":"https:\/\/www.zanolli.it\/wp-content\/uploads\/2022\/03\/Logo-web.png","width":130,"height":39,"caption":"Zanolli"},"image":{"@id":"https:\/\/www.zanolli.it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/products\/3314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/products"}],"about":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/types\/products"}],"author":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/media\/28352"}],"wp:attachment":[{"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/media?parent=3314"}],"wp:term":[{"taxonomy":"campi-applicativi","embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/campi-applicativi?post=3314"},{"taxonomy":"tipologie","embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/tipologie?post=3314"},{"taxonomy":"caratteristiche","embeddable":true,"href":"https:\/\/www.zanolli.it\/fr\/wp-json\/wp\/v2\/caratteristiche?post=3314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}